{"id":9037,"date":"2026-07-06T17:17:57","date_gmt":"2026-07-06T09:17:57","guid":{"rendered":"https:\/\/armorguard.com\/?post_type=product&#038;p=9037"},"modified":"2026-07-06T17:59:17","modified_gmt":"2026-07-06T09:59:17","slug":"double-soft-rifle-case-with-molle","status":"publish","type":"product","link":"https:\/\/armorguard.com\/pt\/product\/double-soft-rifle-case-with-molle\/","title":{"rendered":"Estojo cl\u00e1ssico duplo e macio para espingarda com sistema MOLLE"},"content":{"rendered":"<p>Esta bolsa macia para espingardas foi concebida especificamente para ca\u00e7adores, entusiastas do tiro, utilizadores de campos de tiro e profissionais t\u00e1ticos, proporcionando um armazenamento seguro das armas de fogo, um transporte pr\u00e1tico e uma organiza\u00e7\u00e3o ordenada dos acess\u00f3rios numa \u00fanica solu\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>Saco duplo para armas longas <span id=\"productTitle\" class=\"a-size-large product-title-word-break\">com fecho de correr com bloqueio<\/span><\/p>","protected":false},"featured_media":9048,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[99,109],"product_tag":[],"class_list":{"0":"post-9037","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tactical-bag","7":"product_cat-rifle-bag","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/product\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/comments?post=9037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/media\/9048"}],"wp:attachment":[{"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/product_brand?post=9037"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/product_cat?post=9037"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/armorguard.com\/pt\/wp-json\/wp\/v2\/product_tag?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}